{"id":2986,"date":"2024-07-10T15:27:16","date_gmt":"2024-07-10T13:27:16","guid":{"rendered":"https:\/\/www.svdjk-kleinenberg.de\/?p=2986"},"modified":"2024-07-10T15:27:18","modified_gmt":"2024-07-10T13:27:18","slug":"frauen-gehen-ehrgeizig-in-die-neue-saison","status":"publish","type":"post","link":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/2024\/07\/10\/frauen-gehen-ehrgeizig-in-die-neue-saison\/","title":{"rendered":"Frauen gehen ehrgeizig in die neue Saison"},"content":{"rendered":"\n<p>Dass unsere 1. Frauen-Mannschaft nach dem umjubelten Aufstieg in die Bezirksliga wohl nichts mit Abstieg zu tun haben w\u00fcrde, war vielen klar \u2013 zu stark der Kader. Doch mit einem 4. Platz am Ende der Serie h\u00e4tte doch sicher niemand gerechnet. Was in der Endabrechnung herauskommen wird, sei dahin gestellt \u2013 aber das sehr gute Auftreten des vergangenen Jahres m\u00f6chte das Team um Trainer Robert Herr best\u00e4tigen und das Leistungsniveau auch noch einmal steigern.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1530\" height=\"1148\" src=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/07\/image-3-edited.png\" alt=\"\" class=\"wp-image-2991\" style=\"width:341px;height:auto\" srcset=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/07\/image-3-edited.png 1530w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/07\/image-3-edited-300x225.png 300w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/07\/image-3-edited-1024x768.png 1024w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/07\/image-3-edited-768x576.png 768w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/07\/image-3-edited-1200x900.png 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n<\/div>\n\n\n<p>Dabei ver\u00e4ndert sich der Kader von Robert Herr, der nun auf seinen Co Nikolas Otto verzichten muss, der nach \u00fcber zehn Jahren einen neuen beruflichen und privaten Lebensmittelpunkt hat. Und auch Dominique Lauhoff und Co-Trainer Peter K\u00f6\u00dfmeier k\u00f6nnen sich \u00fcber mehrere Neuzug\u00e4nge freuen:<\/p>\n\n\n\n<p><strong>Neu im Team der 2. Mannschaft:<\/strong><\/p>\n\n\n\n<p>Olivia Ernst (eigene Jugend), Zita Rose (eigene Jugend), Maria Micus (eigene Jugend), Charlotte Heyer (eigene Jugend), Charlotte Fahlbusch (eigene Jugend), Alicia Hoffmann (eigene Jugend), Joanna Brunn (VfR Volkmarsen).<\/p>\n\n\n\n<p><strong>Neu im Team der 1. Mannschaft:<\/strong><\/p>\n\n\n\n<p>Lily Graute (eigene Jugend), Alexandra Meier (eigene Jugend), Katharina Heweling, (FC Germete\/Wormeln), Hannah Johannpeter (FC G\u00fctersloh), Kyra Struttmann (SV Sch\u00f6nstadt)<\/p>\n\n\n\n<p>Seit dieser Woche bitten die Trainer die M\u00e4dels nun zur siebenw\u00f6chigen Vorbereitung auf die neue Spielzeit. Dabei stehen in jeder Woche drei Trainingseinheiten und ein Testspiel auf dem Plan. Am letzten Juli-Wochenende treffen sich die Teams dann zu einem intensiven Trainingswochenende in Kleinenberg.<\/p>\n\n\n\n<p>Die 1. Mannschaft bestreitet Testspiele in Kleinenberg gegen FFC Nethegau, SV Benhausen und Kollerbeck sowie ausw\u00e4rts beim SV Sch\u00f6nstadt.<\/p>\n\n\n\n<p>Die Zweite bestreitet Partien in Kleinenberg gegen FC M\u00f6nninhausen, TuS Lipperode und FC Boffzen und bei der SG Erkeln-Gehrden.<\/p>\n\n\n\n<p>Das erste Meisterschaftsspiel findet am 25. August statt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dass unsere 1. Frauen-Mannschaft nach dem umjubelten Aufstieg in die Bezirksliga wohl nichts mit Abstieg zu tun haben w\u00fcrde, war vielen klar \u2013 zu stark der Kader. Doch mit einem 4. Platz am Ende der Serie h\u00e4tte doch sicher niemand gerechnet. Was in der Endabrechnung herauskommen wird, sei dahin gestellt \u2013 aber das sehr gute &hellip; <a href=\"https:\/\/www.svdjk-kleinenberg.de\/index.php\/2024\/07\/10\/frauen-gehen-ehrgeizig-in-die-neue-saison\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eFrauen gehen ehrgeizig in die neue Saison\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2986","post","type-post","status-publish","format-standard","hentry","category-aktuell"],"_links":{"self":[{"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/posts\/2986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/comments?post=2986"}],"version-history":[{"count":1,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/posts\/2986\/revisions"}],"predecessor-version":[{"id":2992,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/posts\/2986\/revisions\/2992"}],"wp:attachment":[{"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/media?parent=2986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/categories?post=2986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/tags?post=2986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}