{"id":2998,"date":"2024-08-06T17:09:32","date_gmt":"2024-08-06T15:09:32","guid":{"rendered":"https:\/\/www.svdjk-kleinenberg.de\/?p=2998"},"modified":"2024-08-28T11:45:48","modified_gmt":"2024-08-28T09:45:48","slug":"kinder-erlebnis-wochenende","status":"publish","type":"post","link":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/2024\/08\/06\/kinder-erlebnis-wochenende\/","title":{"rendered":"Kinder-Erlebnis-Wochenende"},"content":{"rendered":"\n<p>Viel Nervenkitzel war beim Kinder-Erlebnis-Wochenende am ersten Samstag und Sonntag des Augusts dabei: der Ausflug am Samstagnachmittag in den Kletterwald an die Paderborner Fischteiche war sicher das Highlight der zwei Tage.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"599\" height=\"798\" data-id=\"3030\" src=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.20-3-edited.jpeg\" alt=\"\" class=\"wp-image-3030\" srcset=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.20-3-edited.jpeg 599w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.20-3-edited-225x300.jpeg 225w\" sizes=\"(max-width: 599px) 85vw, 599px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"3029\" src=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.19-1-3-edited-1024x576.jpeg\" alt=\"\" class=\"wp-image-3029\" srcset=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.19-1-3-edited-1024x576.jpeg 1024w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.19-1-3-edited-300x169.jpeg 300w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.19-1-3-edited-768x432.jpeg 768w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.19-1-3-edited-1536x864.jpeg 1536w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.19-1-3-edited-1200x675.jpeg 1200w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.19-1-3-edited.jpeg 1600w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3024\" src=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.20-3-768x1024.jpeg\" alt=\"\" class=\"wp-image-3024\" srcset=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.20-3-768x1024.jpeg 768w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.20-3-225x300.jpeg 225w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.20-3-1152x1536.jpeg 1152w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-16.54.20-3.jpeg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/figure>\n<\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Doch auch dar\u00fcber hinaus sorgte der Jugendausschuss mit seinem Programm f\u00fcr Sport, Spiele und Gemeinschaft nonstop bis zum Sonntagmittag. So traf die Gruppe sich im Anschluss <\/p>\n\n\n\n<p>an den Kletterpark und dem Abendessen zu vielen Aktionen &#8211; wegen des starken Regens &#8211; in der Turnhalle und zum Basteln und Malen im Sportheim.<\/p>\n\n\n\n<p>Den Abend lie\u00dfen die Kids und die Betreuer dann mit dem Stockbrot am Lagerfeuer ausklingen. Am Sonntag fr\u00fchst\u00fcckten alle zusammen und waren mit Ballspielen aktiv bis die Eltern am Vormittag zum Abholen kamen.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3007\" src=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-5-1024x768.png\" alt=\"\" class=\"wp-image-3007\" srcset=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-5-1024x768.png 1024w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-5-300x225.png 300w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-5-768x576.png 768w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-5-1536x1152.png 1536w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-5-1200x900.png 1200w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-5.png 1600w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3006\" src=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-4-768x1024.png\" alt=\"\" class=\"wp-image-3006\" srcset=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-4-768x1024.png 768w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-4-225x300.png 225w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-4-1152x1536.png 1152w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-4.png 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Dieses Mal freuten sich 13 M\u00e4dchen und 11 Jungen auf das Ferienevent. Viele waren nach der Premiere im letzten Jahr zum zweiten Mal mit Begeisterung dabei. Das Wochenende mit \u00dcbernachtung und gemeinsamem Essen wird sicher wiederholt.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"753\" height=\"376\" src=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-6.png\" alt=\"\" class=\"wp-image-3065\" style=\"width:157px;height:auto\" srcset=\"https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-6.png 753w, https:\/\/www.svdjk-kleinenberg.de\/wp-content\/uploads\/2024\/08\/image-6-300x150.png 300w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption class=\"wp-element-caption\">Die Ferienfreizeit wurde finanziell durch die Stiftung des DJK-Sportverbandes unterst\u00fctzt<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Viel Nervenkitzel war beim Kinder-Erlebnis-Wochenende am ersten Samstag und Sonntag des Augusts dabei: der Ausflug am Samstagnachmittag in den Kletterwald an die Paderborner Fischteiche war sicher das Highlight der zwei Tage. Doch auch dar\u00fcber hinaus sorgte der Jugendausschuss mit seinem Programm f\u00fcr Sport, Spiele und Gemeinschaft nonstop bis zum Sonntagmittag. So traf die Gruppe sich &hellip; <a href=\"https:\/\/www.svdjk-kleinenberg.de\/index.php\/2024\/08\/06\/kinder-erlebnis-wochenende\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eKinder-Erlebnis-Wochenende\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2998","post","type-post","status-publish","format-standard","hentry","category-aktuell"],"_links":{"self":[{"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/posts\/2998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/comments?post=2998"}],"version-history":[{"count":11,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/posts\/2998\/revisions"}],"predecessor-version":[{"id":3066,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/posts\/2998\/revisions\/3066"}],"wp:attachment":[{"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/media?parent=2998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/categories?post=2998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.svdjk-kleinenberg.de\/index.php\/wp-json\/wp\/v2\/tags?post=2998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}